{"id":12638,"date":"2024-05-14T12:45:08","date_gmt":"2024-05-14T10:45:08","guid":{"rendered":"https:\/\/www.traghettiup.com\/blog\/?p=12638"},"modified":"2024-05-17T13:53:50","modified_gmt":"2024-05-17T11:53:50","slug":"stabilita-dei-traghetti-la-tecnologia-napa-implementata-sulle-navi-gnv","status":"publish","type":"post","link":"https:\/\/www.traghettiup.com\/blog\/stabilita-dei-traghetti-la-tecnologia-napa-implementata-sulle-navi-gnv\/","title":{"rendered":"Stabilit\u00e0 dei traghetti, la tecnologia NAPA implementata sulle navi GNV"},"content":{"rendered":"\n<p><br>La nuova <strong>soluzione digitale<\/strong> per la stabilit\u00e0 dei traghetti, <strong><em>NAPA Stability for Ferries<\/em><\/strong>, \u00e8 stata implementata su sette <strong>navi della flotta GNV<\/strong>.<\/p>\n\n\n\n<p>Questa innovativa<strong> tecnologia basata su cloud<\/strong> migliora il mantenimento delle condizioni di carico, la trasparenza dei dati e la comunicazione, ottimizzando <strong>sicurezza operativa ed efficienza<\/strong>: la gestione del viaggio e del carico risulta pi\u00f9 rapida e affidabile.<\/p>\n\n\n\n<p>NAPA \u00e8 un fornitore di <strong>software marittimo e servizi dati <\/strong>per la progettazione e le operazioni navali con sede in Finlandia.<\/p>\n\n\n\n<p>La flotta GNV<strong> <\/strong>\u00e8 composta complessivamente da 28 navi; la compagnia di navigazione opera 31 linee in 7 paesi, con <a href=\"https:\/\/www.traghettiup.com\/aree\/sardegna\" data-type=\"link\" data-id=\"https:\/\/www.traghettiup.com\/aree\/sardegna\">traghetti per la Sardegna<\/a> (stagionalmente, per Olbia da Civitavecchia e da Genova e per Porto Torres da Genova), la Sicilia, la Spagna, la Francia, l&#8217;Albania, la Tunisia, il Marocco e Malta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">GNV migliora la stabilit\u00e0 dei traghetti con una soluzione digitale<\/h2>\n\n\n<style>.elementor-627 .elementor-element.elementor-element-73fe466a > .elementor-container > .elementor-column > .elementor-widget-wrap{align-content:center;align-items:center;}.elementor-627 .elementor-element.elementor-element-73fe466a:not(.elementor-motion-effects-element-type-background), .elementor-627 .elementor-element.elementor-element-73fe466a > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#FFE37E;}.elementor-627 .elementor-element.elementor-element-73fe466a, .elementor-627 .elementor-element.elementor-element-73fe466a > .elementor-background-overlay{border-radius:5px 5px 5px 5px;}.elementor-627 .elementor-element.elementor-element-73fe466a{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin-top:40px;margin-bottom:0px;padding:60px 0px 80px 0px;}.elementor-627 .elementor-element.elementor-element-73fe466a > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-627 .elementor-element.elementor-element-4c5a4c19 > .elementor-element-populated, .elementor-627 .elementor-element.elementor-element-4c5a4c19 > .elementor-element-populated > .elementor-background-overlay, .elementor-627 .elementor-element.elementor-element-4c5a4c19 > .elementor-background-slideshow{border-radius:5px 5px 5px 5px;}.elementor-627 .elementor-element.elementor-element-5e651bbf{text-align:center;}.elementor-627 .elementor-element.elementor-element-5e651bbf .elementor-heading-title{color:var( --e-global-color-d7bd849 );font-size:50px;font-weight:600;}.elementor-627 .elementor-element.elementor-element-67c90ba2 .elementor-button{font-size:14px;font-weight:600;text-transform:uppercase;fill:var( --e-global-color-d7bd849 );color:var( --e-global-color-d7bd849 );background-color:#ffffff;border-radius:5px 5px 5px 5px;padding:15px 45px 15px 45px;}.elementor-627 .elementor-element.elementor-element-67c90ba2 .elementor-button:hover, .elementor-627 .elementor-element.elementor-element-67c90ba2 .elementor-button:focus{color:#ffffff;background-color:var( --e-global-color-d7bd849 );}.elementor-627 .elementor-element.elementor-element-67c90ba2 .elementor-button:hover svg, .elementor-627 .elementor-element.elementor-element-67c90ba2 .elementor-button:focus svg{fill:#ffffff;}.elementor-627 .elementor-element.elementor-element-67c90ba2 > .elementor-widget-container{padding:14px 0px 0px 0px;}@media(max-width:1024px){.elementor-627 .elementor-element.elementor-element-73fe466a{padding:100px 25px 100px 25px;}}@media(max-width:767px){.elementor-627 .elementor-element.elementor-element-73fe466a{padding:50px 20px 50px 20px;}.elementor-627 .elementor-element.elementor-element-5e651bbf .elementor-heading-title{font-size:55px;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"627\" class=\"elementor elementor-627\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73fe466a elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73fe466a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c5a4c19\" data-id=\"4c5a4c19\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e651bbf elementor-widget elementor-widget-heading\" data-id=\"5e651bbf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Prenota un traghetto<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67c90ba2 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"67c90ba2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Cerca e compara orari e prezzi<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\n\n\n<p><br><a href=\"https:\/\/www.traghettiup.com\/compagnie\/gnv\" data-type=\"link\" data-id=\"https:\/\/www.traghettiup.com\/compagnie\/gnv\">GNV<\/a> \u00e8 una delle prime compagnie di traghetti ad avvalersi dell&#8217;innovativa tecnologia della <strong>NAPA, sistema di bordo<\/strong> che pu\u00f2 connettersi a terra con una <strong>piattaforma di dati cloud<\/strong> consentendo il monitoraggio continuo e la <strong>regolazione dinamica dei parametri di stabilit\u00e0 della nave in tempo reale<\/strong> da parte dell&#8217;equipaggio e dei team di terra. Ci\u00f2 consente una maggiore efficienza operativa e un processo decisionale pi\u00f9 informato per viaggi sicuri e fluidi.<\/p>\n\n\n\n<p>I dati alla base della tecnologia si basano sull&#8217;accurata modellazione 3D della NAPA, che tiene conto del design unico della nave e la utilizza per coprire un&#8217;ampia gamma di <strong>calcoli relativi all&#8217;idrostatica, alla stabilit\u00e0 intatta, alla stabilit\u00e0 dei danni e alla resistenza longitudinale<\/strong>. <\/p>\n\n\n\n<p>L&#8217;accesso in tempo reale ai dati sulla stabilit\u00e0 offre alle squadre a terra e all&#8217;equipaggio un quadro pi\u00f9 chiaro delle loro attuali condizioni di carico. Ci\u00f2 aiuta a valutare i rischi su base continuativa e fornisce una <strong>migliore comunicazione di informazioni vitali<\/strong> che, in definitiva, supporta una risposta pi\u00f9 rapida in caso di emergenza.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><br>Dichiarazioni alla stampa<\/h3>\n\n\n\n<p>Markus Tompuri, <strong>Chief Stability Officer, Safety Solutions, NAPA<\/strong>, ha dichiarato: &#8220;NAPA Stability for Ferries \u00e8 la nostra risposta alle crescenti sfide di sicurezza ed efficienza del settore. La soluzione avanzata offre il meglio della gestione della stabilit\u00e0, ottimizzata per le operazioni dei traghetti, consentendo loro di attingere a una vasta gamma di informazioni su misura per le loro esigenze specifiche. Lavorare in collaborazione con i leader del settore garantisce inoltre che stiamo costruendo una soluzione che non solo soddisfi i loro obiettivi operativi ma supporti anche il processo decisionale critico, spesso in tempi stretti&#8221;.<\/p>\n\n\n\n<p>Davide Orecchia, <strong>Direttore Tecnico di GNV<\/strong>, ha dichiarato: &#8220;La sicurezza dei nostri passeggeri \u00e8 la nostra massima priorit\u00e0. Lavorare con NAPA ci d\u00e0 la tranquillit\u00e0 di mantenere gli standard pi\u00f9 elevati del settore per garantire che i nostri traghetti operino in modo sicuro e senza intoppi, sbloccando allo stesso tempo informazioni dettagliate sui dati per migliorare l&#8217;efficienza della nostra flotta e dei nostri team. Con nuove funzionalit\u00e0 dinamiche di carico del carico e dati sulla stabilit\u00e0 di bordo in tempo reale disponibili a terra tramite servizi cloud, i nostri team di bordo e di terra possono comunicare e collaborare come mai prima d&#8217;ora&#8221;.<\/p>\n\n\n\n<p>Paolo Astarita, <strong>Chief Nautical Operations Officer di GNV<\/strong>, ha aggiunto: &#8220;L&#8217;installazione di NAPA Stability sulla nostra flotta rappresenta un passo fondamentale nel nostro processo di evoluzione della sicurezza della navigazione. Questa soluzione avanzata di gestione della stabilit\u00e0 supporter\u00e0 i nostri capitani in diverse circostanze, come i passaggi in mare, le prestazioni di carico delle merci, la movimentazione delle navi, i processi di efficienza e la gestione delle criticit\u00e0.<\/p>\n\n\n\n<p>&#8220;Dal lato della riva, avvantaggiano i nostri ufficiali in servizio presso il Centro di supporto marittimo GNV, che operano 24 ore su 24, 7 giorni su 7, per raccogliere da remoto informazioni sulla stabilit\u00e0 in tempo reale. In precedenza abbiamo utilizzato il software NAPA per il carico e abbiamo anche collaborato con la NAPA per la formazione degli ufficiali di coperta.<\/p>\n\n\n\n<p>L&#8217;azienda \u00e8 pronta a migliorare la <strong>sicurezza della flotta <\/strong>e ad adottare i pi\u00f9 recenti requisiti IMO, e siamo lieti di accogliere la nuova evoluzione del software&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La regolazione dei parametri di stabilit\u00e0 di alcune navi GNV viene effettuata in tempo reale con un sistema di bordo che pu\u00f2 connettersi con una piattaforma di dati cloud.<\/p>\n","protected":false},"author":3,"featured_media":12640,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-12638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatti-e-approfondimenti"],"_links":{"self":[{"href":"https:\/\/www.traghettiup.com\/blog\/wp-json\/wp\/v2\/posts\/12638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.traghettiup.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.traghettiup.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.traghettiup.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.traghettiup.com\/blog\/wp-json\/wp\/v2\/comments?post=12638"}],"version-history":[{"count":8,"href":"https:\/\/www.traghettiup.com\/blog\/wp-json\/wp\/v2\/posts\/12638\/revisions"}],"predecessor-version":[{"id":12665,"href":"https:\/\/www.traghettiup.com\/blog\/wp-json\/wp\/v2\/posts\/12638\/revisions\/12665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.traghettiup.com\/blog\/wp-json\/wp\/v2\/media\/12640"}],"wp:attachment":[{"href":"https:\/\/www.traghettiup.com\/blog\/wp-json\/wp\/v2\/media?parent=12638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.traghettiup.com\/blog\/wp-json\/wp\/v2\/categories?post=12638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.traghettiup.com\/blog\/wp-json\/wp\/v2\/tags?post=12638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}